{"id":197,"date":"2022-12-20T04:07:38","date_gmt":"2022-12-20T04:07:38","guid":{"rendered":"https:\/\/my-iq-tester.com\/blog\/?p=194"},"modified":"2026-05-05T05:43:07","modified_gmt":"2026-05-05T05:43:07","slug":"lhistoire-sombre-des-tests-de-qi","status":"publish","type":"post","link":"https:\/\/my-iq-tester.com\/blog\/fr\/lhistoire-sombre-des-tests-de-qi\/","title":{"rendered":"La sombre histoire des tests de QI"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En 1905, les psychologues Alfred Binet et Th\u00e9odore Simon ont con\u00e7u un test pour les enfants en difficult\u00e9 scolaire en France.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con\u00e7ue pour d\u00e9terminer quels enfants n\u00e9cessitaient une attention individualis\u00e9e, leur m\u00e9thode constituait la base du test de QI. \u00c0 partir de la fin du 19\u00e8me si\u00e8cle, les chercheurs ont \u00e9mis l\u2019hypoth\u00e8se que les capacit\u00e9s cognitives telles que le raisonnement verbal, la m\u00e9moire de travail et les comp\u00e9tences visuo-spatiales refl\u00e9taient une intelligence g\u00e9n\u00e9rale sous-jacente, ou facteur g.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Simon et Binet ont con\u00e7u une batterie de tests pour mesurer chacune de ces capacit\u00e9s et combiner les r\u00e9sultats en un seul score.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les questions ont \u00e9t\u00e9 ajust\u00e9es pour chaque groupe d\u2019\u00e2ge, et le score d\u2019un enfant refl\u00e9tait sa performance par rapport aux autres de son \u00e2ge.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En divisant le score d\u2019une personne par son \u00e2ge et en multipliant le r\u00e9sultat par 100, on obtient le quotient intellectuel, ou IQ.Today, un score de 100 repr\u00e9sente la moyenne d\u2019une population \u00e9chantillonn\u00e9e, 68% de la population se situant \u00e0 moins de 15 points sur 100.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Simon et Binet pensaient que les comp\u00e9tences \u00e9valu\u00e9es par leur test refl\u00e9teraient l\u2019intelligence g\u00e9n\u00e9rale. Mais \u00e0 l\u2019\u00e9poque comme aujourd\u2019hui, il n\u2019y a pas de d\u00e9finition unique de l\u2019intelligence g\u00e9n\u00e9rale. Et cela laissait la porte ouverte aux gens pour utiliser le service testin de leurs propres hypoth\u00e8ses pr\u00e9con\u00e7ues sur l\u2019intelligence.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce qui a commenc\u00e9 comme un moyen d\u2019identifier ceux qui avaient besoin d\u2019aide acad\u00e9mique a rapidement \u00e9t\u00e9 utilis\u00e9 pour trier les gens d\u2019une autre mani\u00e8re, souvent au service d\u2019id\u00e9ologies profond\u00e9ment erron\u00e9es. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019une des premi\u00e8res mises en \u0153uvre \u00e0 grande \u00e9chelle a eu lieu aux \u00c9tats-Unis pendant la Premi\u00e8re Guerre mondiale, lorsque l\u2019arm\u00e9e a utilis\u00e9 un test de QI pour trier les recrues et les s\u00e9lectionner pour la formation des officiers.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 cette \u00e9poque, beaucoup de gens croyaient en l\u2019eug\u00e9nisme, l\u2019id\u00e9e que les traits g\u00e9n\u00e9tiques souhaitables et ind\u00e9sirables pouvaient et devaient \u00eatre contr\u00f4l\u00e9s chez l\u2019homme par la reproduction s\u00e9lective. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il y avait beaucoup de probl\u00e8mes avec cette ligne de pens\u00e9e, parmi eux l\u2019id\u00e9e que l\u2019intelligence n\u2019\u00e9tait pas seulement fixe et h\u00e9rit\u00e9e, mais aussi li\u00e9e \u00e0 la race d\u2019une personne.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sous l\u2019influence de l\u2019eug\u00e9nisme, les scientifiques ont utilis\u00e9 les r\u00e9sultats de l\u2019initiative militaire pour affirmer \u00e0 tort que certains groupes raciaux \u00e9taient intellectuellement sup\u00e9rieurs \u00e0 d\u2019autres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sans tenir compte du fait que bon nombre des recrues test\u00e9es \u00e9taient de nouveaux immigrants aux \u00c9tats-Unis qui n\u2019avaient pas re\u00e7u d\u2019\u00e9ducation formelle ou d\u2019exposition \u00e0 la langue anglaise, ils ont cr\u00e9\u00e9 une hi\u00e9rarchie erron\u00e9e des groupes ethniques.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019intersection de l\u2019eug\u00e9nisme et des tests de QI a influenc\u00e9 non seulement la science, mais aussi la politique. En 1924, l\u2019\u00c9tat de Virginie a cr\u00e9\u00e9 une politique permettant la st\u00e9rilisation forc\u00e9e des personnes ayant un faible score de QI \u2013 une d\u00e9cision confirm\u00e9e par la Cour supr\u00eame des \u00c9tats-Unis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans l\u2019Allemagne nazie, le gouvernement a autoris\u00e9 le meurtre d\u2019enfants sur la base d\u2019un faible QI. Apr\u00e8s l\u2019Holocauste et le mouvement des droits civiques, les utilisations discriminatoires des tests de QI ont \u00e9t\u00e9 contest\u00e9es pour des raisons \u00e0 la fois morales et scientifiques.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les scientifiques ont commenc\u00e9 \u00e0 recueillir des preuves des impacts environnementaux sur le QI. Par exemple, comme les tests de QI ont \u00e9t\u00e9 p\u00e9riodiquement recalibr\u00e9s au cours du 20e si\u00e8cle, les nouvelles g\u00e9n\u00e9rations ont obtenu des r\u00e9sultats syst\u00e9matiquement plus \u00e9lev\u00e9s aux anciens tests que chaque g\u00e9n\u00e9ration pr\u00e9c\u00e9dente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce ph\u00e9nom\u00e8ne, connu sous le nom d\u2019effet Flynn, s\u2019est produit beaucoup trop vite pour \u00eatre caus\u00e9 par des traits \u00e9volutifs h\u00e9r\u00e9ditaires.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au lieu de cela, la cause \u00e9tait probablement environnementale \u2013 une meilleure \u00e9ducation, de meilleurs soins de sant\u00e9 et une meilleure nutrition. Au milieu du XXe si\u00e8cle, les psychologues ont \u00e9galement tent\u00e9 d\u2019utiliser des tests de QI pour \u00e9valuer des choses autres que l\u2019intelligence g\u00e9n\u00e9rale, en particulier la schizophr\u00e9nie, la d\u00e9pression et d\u2019autres troubles psychiatriques. Ces diagnostics reposaient en partie sur le jugement clinique des \u00e9valuateurs et utilisaient un sous-ensemble de tests utilis\u00e9s pour d\u00e9terminer le QI \u2013 une pratique qui, selon des recherches ult\u00e9rieures, ne fournit pas d\u2019informations cliniquement utiles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aujourd\u2019hui, les tests de QI utilisent de nombreux \u00e9l\u00e9ments de conception et types de questions similaires \u00e0 ceux des premiers tests, bien que nous ayons de meilleures techniques pour identifier les biais potentiels dans le test.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ils ne sont plus utilis\u00e9s pour diagnostiquer les troubles psychiatriques. Mais une pratique tout aussi probl\u00e9matique utilisant les r\u00e9sultats des sous-tests est encore parfois utilis\u00e9e pour diagnostiquer les troubles d\u2019apprentissage, contre l\u2019avis de nombreux experts.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les psychologues du monde entier utilisent encore des tests de QI pour identifier la d\u00e9ficience intellectuelle, et les r\u00e9sultats peuvent \u00eatre utilis\u00e9s pour d\u00e9terminer le soutien \u00e9ducatif appropri\u00e9, la formation professionnelle et l\u2019aide \u00e0 la vie autonome. Les r\u00e9sultats des tests de QI ont \u00e9t\u00e9 utilis\u00e9s pour justifier des politiques horribles et des id\u00e9ologies scientifiquement sans fondement.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cela ne signifie pas que le test lui-m\u00eame est sans valeur \u2013 en fait, il fait un bon travail de mesure des comp\u00e9tences de raisonnement et de r\u00e9solution de probl\u00e8mes qu\u2019il vise. Mais ce n\u2019est pas la m\u00eame chose que de mesurer le potentiel d\u2019une personne.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bien qu\u2019il existe de nombreuses questions politiques, historiques, scientifiques et culturelles complexes envelopp\u00e9es dans les tests de QI, de plus en plus de chercheurs sont d\u2019accord sur ce point et rejettent l\u2019id\u00e9e que les individus peuvent \u00eatre cat\u00e9goris\u00e9s par un seul score num\u00e9rique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En 1905, les psychologues Alfred Binet et Th\u00e9odore Simon ont con\u00e7u un test pour les enfants en difficult\u00e9 scolaire en France. Con\u00e7ue pour d\u00e9terminer quels enfants n\u00e9cessitaient une attention individualis\u00e9e, leur m\u00e9thode constituait la base du test de QI. \u00c0 partir de la fin du 19\u00e8me si\u00e8cle, les chercheurs ont \u00e9mis l\u2019hypoth\u00e8se que les capacit\u00e9s&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[7],"tags":[],"class_list":["post-197","post","type-post","status-publish","format-standard","hentry","category-qi-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La sombre histoire des tests de QI<\/title>\n<meta name=\"description\" content=\"Explorez la sombre histoire des tests de QI, leurs usages controvers\u00e9s, les enjeux \u00e9thiques et le contexte des tests modernes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/my-iq-tester.com\/blog\/fr\/lhistoire-sombre-des-tests-de-qi\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La sombre histoire des tests de QI\" \/>\n<meta property=\"og:description\" content=\"Explorez la sombre histoire des tests de QI, leurs usages controvers\u00e9s, les enjeux \u00e9thiques et le contexte des tests modernes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/my-iq-tester.com\/blog\/fr\/lhistoire-sombre-des-tests-de-qi\/\" \/>\n<meta property=\"og:site_name\" content=\"My IQ Tester\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-20T04:07:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-05T05:43:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/my-iq-tester.com\/blog\/wp-content\/uploads\/2026\/01\/cropped-logo-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"My IQ Tester Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"La sombre histoire des tests de QI\" \/>\n<meta name=\"twitter:description\" content=\"Explorez la sombre histoire des tests de QI, leurs usages controvers\u00e9s, les enjeux \u00e9thiques et le contexte des tests modernes.\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"My IQ Tester Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/my-iq-tester.com\\\/blog\\\/fr\\\/lhistoire-sombre-des-tests-de-qi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/my-iq-tester.com\\\/blog\\\/fr\\\/lhistoire-sombre-des-tests-de-qi\\\/\"},\"author\":{\"name\":\"My IQ Tester Team\",\"@id\":\"https:\\\/\\\/my-iq-tester.com\\\/blog\\\/#\\\/schema\\\/person\\\/fea4613f54a1a5eddc9346d0ffe8ff3d\"},\"headline\":\"La sombre histoire des tests de QI\",\"datePublished\":\"2022-12-20T04:07:38+00:00\",\"dateModified\":\"2026-05-05T05:43:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/my-iq-tester.com\\\/blog\\\/fr\\\/lhistoire-sombre-des-tests-de-qi\\\/\"},\"wordCount\":1035,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/my-iq-tester.com\\\/blog\\\/#organization\"},\"articleSection\":[\"QI\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/my-iq-tester.com\\\/blog\\\/fr\\\/lhistoire-sombre-des-tests-de-qi\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/my-iq-tester.com\\\/blog\\\/fr\\\/lhistoire-sombre-des-tests-de-qi\\\/\",\"url\":\"https:\\\/\\\/my-iq-tester.com\\\/blog\\\/fr\\\/lhistoire-sombre-des-tests-de-qi\\\/\",\"name\":\"La sombre histoire des tests de QI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/my-iq-tester.com\\\/blog\\\/#website\"},\"datePublished\":\"2022-12-20T04:07:38+00:00\",\"dateModified\":\"2026-05-05T05:43:07+00:00\",\"description\":\"Explorez la sombre histoire des tests de QI, leurs usages controvers\u00e9s, les enjeux \u00e9thiques et le contexte des tests modernes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/my-iq-tester.com\\\/blog\\\/fr\\\/lhistoire-sombre-des-tests-de-qi\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/my-iq-tester.com\\\/blog\\\/fr\\\/lhistoire-sombre-des-tests-de-qi\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/my-iq-tester.com\\\/blog\\\/fr\\\/lhistoire-sombre-des-tests-de-qi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/my-iq-tester.com\\\/blog\\\/zh\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La sombre histoire des tests de QI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/my-iq-tester.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/my-iq-tester.com\\\/blog\\\/\",\"name\":\"My IQ Tester\",\"description\":\"Take IQ test 2026 now using The most accurate official IQ test available online. Test your IQ and get your results immediately.\",\"publisher\":{\"@id\":\"https:\\\/\\\/my-iq-tester.com\\\/blog\\\/#organization\"},\"alternateName\":\"MyIQTester\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/my-iq-tester.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/my-iq-tester.com\\\/blog\\\/#organization\",\"name\":\"MyIQTester\",\"url\":\"https:\\\/\\\/my-iq-tester.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/my-iq-tester.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/my-iq-tester.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/my-iq-tester.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/logo.png\",\"width\":261,\"height\":261,\"caption\":\"MyIQTester\"},\"image\":{\"@id\":\"https:\\\/\\\/my-iq-tester.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/my-iq-tester.com\\\/blog\\\/#\\\/schema\\\/person\\\/fea4613f54a1a5eddc9346d0ffe8ff3d\",\"name\":\"My IQ Tester Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/my-iq-tester.com\\\/blog\\\/wp-content\\\/litespeed\\\/avatar\\\/33b3a83e0b9834b5d5dfffd3ccb8c148.jpg?ver=1784066489\",\"url\":\"https:\\\/\\\/my-iq-tester.com\\\/blog\\\/wp-content\\\/litespeed\\\/avatar\\\/33b3a83e0b9834b5d5dfffd3ccb8c148.jpg?ver=1784066489\",\"contentUrl\":\"https:\\\/\\\/my-iq-tester.com\\\/blog\\\/wp-content\\\/litespeed\\\/avatar\\\/33b3a83e0b9834b5d5dfffd3ccb8c148.jpg?ver=1784066489\",\"caption\":\"My IQ Tester Team\"},\"sameAs\":[\"https:\\\/\\\/my-iq-tester.com\\\/blog\\\/\"],\"url\":\"https:\\\/\\\/my-iq-tester.com\\\/blog\\\/author\\\/iqtester\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La sombre histoire des tests de QI","description":"Explorez la sombre histoire des tests de QI, leurs usages controvers\u00e9s, les enjeux \u00e9thiques et le contexte des tests modernes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/my-iq-tester.com\/blog\/fr\/lhistoire-sombre-des-tests-de-qi\/","og_locale":"es_ES","og_type":"article","og_title":"La sombre histoire des tests de QI","og_description":"Explorez la sombre histoire des tests de QI, leurs usages controvers\u00e9s, les enjeux \u00e9thiques et le contexte des tests modernes.","og_url":"https:\/\/my-iq-tester.com\/blog\/fr\/lhistoire-sombre-des-tests-de-qi\/","og_site_name":"My IQ Tester","article_published_time":"2022-12-20T04:07:38+00:00","article_modified_time":"2026-05-05T05:43:07+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/my-iq-tester.com\/blog\/wp-content\/uploads\/2026\/01\/cropped-logo-1.png","type":"image\/png"}],"author":"My IQ Tester Team","twitter_card":"summary_large_image","twitter_title":"La sombre histoire des tests de QI","twitter_description":"Explorez la sombre histoire des tests de QI, leurs usages controvers\u00e9s, les enjeux \u00e9thiques et le contexte des tests modernes.","twitter_misc":{"Escrito por":"My IQ Tester Team","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/my-iq-tester.com\/blog\/fr\/lhistoire-sombre-des-tests-de-qi\/#article","isPartOf":{"@id":"https:\/\/my-iq-tester.com\/blog\/fr\/lhistoire-sombre-des-tests-de-qi\/"},"author":{"name":"My IQ Tester Team","@id":"https:\/\/my-iq-tester.com\/blog\/#\/schema\/person\/fea4613f54a1a5eddc9346d0ffe8ff3d"},"headline":"La sombre histoire des tests de QI","datePublished":"2022-12-20T04:07:38+00:00","dateModified":"2026-05-05T05:43:07+00:00","mainEntityOfPage":{"@id":"https:\/\/my-iq-tester.com\/blog\/fr\/lhistoire-sombre-des-tests-de-qi\/"},"wordCount":1035,"commentCount":0,"publisher":{"@id":"https:\/\/my-iq-tester.com\/blog\/#organization"},"articleSection":["QI"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/my-iq-tester.com\/blog\/fr\/lhistoire-sombre-des-tests-de-qi\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/my-iq-tester.com\/blog\/fr\/lhistoire-sombre-des-tests-de-qi\/","url":"https:\/\/my-iq-tester.com\/blog\/fr\/lhistoire-sombre-des-tests-de-qi\/","name":"La sombre histoire des tests de QI","isPartOf":{"@id":"https:\/\/my-iq-tester.com\/blog\/#website"},"datePublished":"2022-12-20T04:07:38+00:00","dateModified":"2026-05-05T05:43:07+00:00","description":"Explorez la sombre histoire des tests de QI, leurs usages controvers\u00e9s, les enjeux \u00e9thiques et le contexte des tests modernes.","breadcrumb":{"@id":"https:\/\/my-iq-tester.com\/blog\/fr\/lhistoire-sombre-des-tests-de-qi\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/my-iq-tester.com\/blog\/fr\/lhistoire-sombre-des-tests-de-qi\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/my-iq-tester.com\/blog\/fr\/lhistoire-sombre-des-tests-de-qi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/my-iq-tester.com\/blog\/zh\/"},{"@type":"ListItem","position":2,"name":"La sombre histoire des tests de QI"}]},{"@type":"WebSite","@id":"https:\/\/my-iq-tester.com\/blog\/#website","url":"https:\/\/my-iq-tester.com\/blog\/","name":"My IQ Tester","description":"Take IQ test 2026 now using The most accurate official IQ test available online. Test your IQ and get your results immediately.","publisher":{"@id":"https:\/\/my-iq-tester.com\/blog\/#organization"},"alternateName":"MyIQTester","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/my-iq-tester.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/my-iq-tester.com\/blog\/#organization","name":"MyIQTester","url":"https:\/\/my-iq-tester.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/my-iq-tester.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/my-iq-tester.com\/blog\/wp-content\/uploads\/2022\/05\/logo.png","contentUrl":"https:\/\/my-iq-tester.com\/blog\/wp-content\/uploads\/2022\/05\/logo.png","width":261,"height":261,"caption":"MyIQTester"},"image":{"@id":"https:\/\/my-iq-tester.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/my-iq-tester.com\/blog\/#\/schema\/person\/fea4613f54a1a5eddc9346d0ffe8ff3d","name":"My IQ Tester Team","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/my-iq-tester.com\/blog\/wp-content\/litespeed\/avatar\/33b3a83e0b9834b5d5dfffd3ccb8c148.jpg?ver=1784066489","url":"https:\/\/my-iq-tester.com\/blog\/wp-content\/litespeed\/avatar\/33b3a83e0b9834b5d5dfffd3ccb8c148.jpg?ver=1784066489","contentUrl":"https:\/\/my-iq-tester.com\/blog\/wp-content\/litespeed\/avatar\/33b3a83e0b9834b5d5dfffd3ccb8c148.jpg?ver=1784066489","caption":"My IQ Tester Team"},"sameAs":["https:\/\/my-iq-tester.com\/blog\/"],"url":"https:\/\/my-iq-tester.com\/blog\/author\/iqtester\/"}]}},"_links":{"self":[{"href":"https:\/\/my-iq-tester.com\/blog\/wp-json\/wp\/v2\/posts\/197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/my-iq-tester.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/my-iq-tester.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/my-iq-tester.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/my-iq-tester.com\/blog\/wp-json\/wp\/v2\/comments?post=197"}],"version-history":[{"count":1,"href":"https:\/\/my-iq-tester.com\/blog\/wp-json\/wp\/v2\/posts\/197\/revisions"}],"predecessor-version":[{"id":721,"href":"https:\/\/my-iq-tester.com\/blog\/wp-json\/wp\/v2\/posts\/197\/revisions\/721"}],"wp:attachment":[{"href":"https:\/\/my-iq-tester.com\/blog\/wp-json\/wp\/v2\/media?parent=197"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/my-iq-tester.com\/blog\/wp-json\/wp\/v2\/categories?post=197"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/my-iq-tester.com\/blog\/wp-json\/wp\/v2\/tags?post=197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}